{"id":20,"date":"2022-11-10T10:18:29","date_gmt":"2022-11-10T10:18:29","guid":{"rendered":"https:\/\/tourandtravelkerala.com\/index.php\/destination\/"},"modified":"2022-11-16T10:53:33","modified_gmt":"2022-11-16T10:53:33","slug":"destination","status":"publish","type":"page","link":"https:\/\/tourandtravelkerala.com\/index.php\/destination\/","title":{"rendered":"Select your favourite Cities"},"content":{"rendered":"\n<ul class=\"has-medium-font-size\">\n<li>Cochin<\/li>\n\n\n\n<li>Thrrisur<\/li>\n\n\n\n<li>Guruvayoor<\/li>\n\n\n\n<li>Calicut<\/li>\n\n\n\n<li>Kannur<\/li>\n\n\n\n<li>Wayand\n<ul>\n<li><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<ul>\n<li>Palakkad<\/li>\n\n\n\n<li>Munnar<\/li>\n\n\n\n<li>Thekkady<\/li>\n\n\n\n<li>Vagamon<\/li>\n\n\n\n<li>Ramakkalmedu<\/li>\n\n\n\n<li>Mararikulam<\/li>\n\n\n\n<li>Cherai<\/li>\n\n\n\n<li>Alleppey<\/li>\n<\/ul>\n\n\n\n\n\n\n\n<ul>\n<li>Varkala<\/li>\n\n\n\n<li>Ashtamudi<\/li>\n\n\n\n<li>Kovalam<\/li>\n\n\n\n<li>Kanyakumari<\/li>\n\n\n\n<li>Rameswaram<\/li>\n\n\n\n<li>Madurai<\/li>\n\n\n\n<li>Kodaikanal<\/li>\n\n\n\n<li>Ooty<\/li>\n<\/ul>\n\n\n\n\n\n\n\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-destination.php","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Select your favourite Cities - Make your Memorable Kerala Holiday Packages Best Tour Operator from Kerala, Cochin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tourandtravelkerala.com\/index.php\/destination\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Select your favourite Cities - Make your Memorable Kerala Holiday Packages Best Tour Operator from Kerala, Cochin\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tourandtravelkerala.com\/index.php\/destination\/\" \/>\n<meta property=\"og:site_name\" content=\"Make your Memorable Kerala Holiday Packages Best Tour Operator from Kerala, Cochin\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-16T10:53:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tourandtravelkerala.com\/index.php\/destination\/\",\"url\":\"https:\/\/tourandtravelkerala.com\/index.php\/destination\/\",\"name\":\"Select your favourite Cities - Make your Memorable Kerala Holiday Packages Best Tour Operator from Kerala, Cochin\",\"isPartOf\":{\"@id\":\"https:\/\/tourandtravelkerala.com\/#website\"},\"datePublished\":\"2022-11-10T10:18:29+00:00\",\"dateModified\":\"2022-11-16T10:53:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tourandtravelkerala.com\/index.php\/destination\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tourandtravelkerala.com\/index.php\/destination\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tourandtravelkerala.com\/index.php\/destination\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/tourandtravelkerala.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Select your favourite Cities\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tourandtravelkerala.com\/#website\",\"url\":\"https:\/\/tourandtravelkerala.com\/\",\"name\":\"Make your Memorable Kerala Holiday Packages Best Tour Operator from Kerala, Cochin\",\"description\":\"Best Tour &amp; Travel Operator in Kerala , Kerala Best vacation Planner\",\"publisher\":{\"@id\":\"https:\/\/tourandtravelkerala.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tourandtravelkerala.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tourandtravelkerala.com\/#organization\",\"name\":\"Make your Memorable Kerala Holiday Packages Best Tour Operator from Kerala, Cochin\",\"url\":\"https:\/\/tourandtravelkerala.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/tourandtravelkerala.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tourandtravelkerala.com\/wp-content\/uploads\/2022\/12\/Untitled.png\",\"contentUrl\":\"https:\/\/tourandtravelkerala.com\/wp-content\/uploads\/2022\/12\/Untitled.png\",\"width\":819,\"height\":460,\"caption\":\"Make your Memorable Kerala Holiday Packages Best Tour Operator from Kerala, Cochin\"},\"image\":{\"@id\":\"https:\/\/tourandtravelkerala.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Select your favourite Cities - Make your Memorable Kerala Holiday Packages Best Tour Operator from Kerala, Cochin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tourandtravelkerala.com\/index.php\/destination\/","og_locale":"en_US","og_type":"article","og_title":"Select your favourite Cities - Make your Memorable Kerala Holiday Packages Best Tour Operator from Kerala, Cochin","og_url":"https:\/\/tourandtravelkerala.com\/index.php\/destination\/","og_site_name":"Make your Memorable Kerala Holiday Packages Best Tour Operator from Kerala, Cochin","article_modified_time":"2022-11-16T10:53:33+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tourandtravelkerala.com\/index.php\/destination\/","url":"https:\/\/tourandtravelkerala.com\/index.php\/destination\/","name":"Select your favourite Cities - Make your Memorable Kerala Holiday Packages Best Tour Operator from Kerala, Cochin","isPartOf":{"@id":"https:\/\/tourandtravelkerala.com\/#website"},"datePublished":"2022-11-10T10:18:29+00:00","dateModified":"2022-11-16T10:53:33+00:00","breadcrumb":{"@id":"https:\/\/tourandtravelkerala.com\/index.php\/destination\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tourandtravelkerala.com\/index.php\/destination\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tourandtravelkerala.com\/index.php\/destination\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tourandtravelkerala.com\/"},{"@type":"ListItem","position":2,"name":"Select your favourite Cities"}]},{"@type":"WebSite","@id":"https:\/\/tourandtravelkerala.com\/#website","url":"https:\/\/tourandtravelkerala.com\/","name":"Make your Memorable Kerala Holiday Packages Best Tour Operator from Kerala, Cochin","description":"Best Tour &amp; Travel Operator in Kerala , Kerala Best vacation Planner","publisher":{"@id":"https:\/\/tourandtravelkerala.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tourandtravelkerala.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/tourandtravelkerala.com\/#organization","name":"Make your Memorable Kerala Holiday Packages Best Tour Operator from Kerala, Cochin","url":"https:\/\/tourandtravelkerala.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tourandtravelkerala.com\/#\/schema\/logo\/image\/","url":"https:\/\/tourandtravelkerala.com\/wp-content\/uploads\/2022\/12\/Untitled.png","contentUrl":"https:\/\/tourandtravelkerala.com\/wp-content\/uploads\/2022\/12\/Untitled.png","width":819,"height":460,"caption":"Make your Memorable Kerala Holiday Packages Best Tour Operator from Kerala, Cochin"},"image":{"@id":"https:\/\/tourandtravelkerala.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/tourandtravelkerala.com\/index.php\/wp-json\/wp\/v2\/pages\/20"}],"collection":[{"href":"https:\/\/tourandtravelkerala.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tourandtravelkerala.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tourandtravelkerala.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tourandtravelkerala.com\/index.php\/wp-json\/wp\/v2\/comments?post=20"}],"version-history":[{"count":4,"href":"https:\/\/tourandtravelkerala.com\/index.php\/wp-json\/wp\/v2\/pages\/20\/revisions"}],"predecessor-version":[{"id":60,"href":"https:\/\/tourandtravelkerala.com\/index.php\/wp-json\/wp\/v2\/pages\/20\/revisions\/60"}],"wp:attachment":[{"href":"https:\/\/tourandtravelkerala.com\/index.php\/wp-json\/wp\/v2\/media?parent=20"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}